{"id":40237,"date":"2019-12-09T14:21:13","date_gmt":"2019-12-09T13:21:13","guid":{"rendered":"https:\/\/www.ave.it\/prodotto\/blas1\/"},"modified":"2026-05-13T05:32:04","modified_gmt":"2026-05-13T03:32:04","slug":"blas1","status":"publish","type":"product","link":"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/","title":{"rendered":"BLAS1"},"content":{"rendered":"<p>{&#8220;Prezzo&#8221;:{&#8220;Prezzo&#8221;:&#8221;0,93&#8243;},&#8221;Descrizione&#8221;:{&#8220;Descrizione&#8221;:&#8221;Giunto unione per scatole di derivazione da incasso: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36&#8243;,&#8221;Descrizione estesa&#8221;:&#8221;Giunto d&#039;unione o dispositivo di accoppiamento, che consente di mantenere alla giusta distanza le scatole durante le operazioni di muratura, per scatole di derivazione multifunzione: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36&#8243;},&#8221;Dati commerciali&#8221;:{&#8220;Codice EAN13&#8243;:&#8221;8008379022205&#8243;,&#8221;Imballo standard&#8221;:&#8221;1,00&#8243;,&#8221;Imballo minimo&#8221;:&#8221;20,00&#8243;,&#8221;Codice EAN13 imb.min.&#8221;:&#8221;8008379215492&#8243;,&#8221;Lunghezza imb. min.&#8221;:&#8221;90,00&#8243;,&#8221;Larghezza imb. min.&#8221;:&#8221;35,00&#8243;,&#8221;Altezza imb. min.&#8221;:&#8221;110,00&#8243;,&#8221;Volume imb. min.&#8221;:&#8221;0,34&#8243;,&#8221;Peso imb. min.&#8221;:&#8221;70,00&#8243;,&#8221;Quantit\\u00e0 min. ordine&#8221;:&#8221;20,00&#8243;,&#8221;Riferimento Metel&#8221;:&#8221;GIUNTO UNIONE X SCATOLE DERIVAZIONE&#8221;,&#8221;Stato prodotto&#8221;:&#8221;A Magazzino&#8221;},&#8221;Categorizzazione&#8221;:{&#8220;Serie&#8221;:&#8221;404&#8243;,&#8221;Divisione&#8221;:&#8221;4&#8243;,&#8221;GP&#8221;:&#8221;25&#8243;,&#8221;Classe&#8221;:&#8221;EC002328&#8243;},&#8221;Marchi senza file&#8221;:{&#8220;I.M.Q.&#8221;:&#8221;I.M.Q.&#8221;},&#8221;Dati tecnici ETIM&#8221;:{&#8220;Tipo di accessorio\\\/parte di ricambio&#8221;:&#8221;Elemento di raccordo&#8221;,&#8221;Adatto per scatola centrale&#8221;:&#8221;No&#8221;,&#8221;Adatto per scatola da incasso&#8221;:&#8221;Si&#8221;,&#8221;Accessorio&#8221;:&#8221;Si&#8221;,&#8221;Parte di ricambio&#8221;:&#8221;Si&#8221;},&#8221;Pagina Catalogo Commerciale&#8221;:{&#8220;Pagina catalogo Pag353&#8243;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/D000000234.pdf&#8221;},&#8221;Ingombro (PNG)&#8221;:{&#8220;BLAS1&#8243;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/0000014473.png&#8221;},&#8221;Immagini Articolo&#8221;:{&#8220;BLAS1&#8243;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/A000005323.jpg&#8221;},&#8221;Ingombro (STL)&#8221;:{&#8220;SOLIDO STL&#8221;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/0000012384.stl&#8221;},&#8221;Ingombro (STP)&#8221;:{&#8220;SOLIDO STEP&#8221;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/0000012383.stp&#8221;},&#8221;Ingombro (DXF)&#8221;:{&#8220;INGOMBRO DXF&#8221;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/0000012382.dxf&#8221;},&#8221;Data ultimo aggiornamento&#8221;:{&#8220;Data ultimo aggiornamento&#8221;:&#8221;02-03-2026&#8243;}}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Giunto d&#039;unione o dispositivo di accoppiamento, che consente di mantenere alla giusta distanza le scatole durante le operazioni di muratura, per scatole di derivazione multifunzione: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36<\/p>\n","protected":false},"featured_media":251421,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3624,3632,3633],"product_tag":[3634],"class_list":{"0":"post-40237","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-scatole-contenitori-e-centralini","7":"product_cat-scatole-da-incasso-per-serie-civili","8":"product_cat-accessori-per-scatole-per-pareti-in-muratura","9":"product_tag-accessori-per-scatole-per-pareti-in-muratura","11":"first","12":"instock","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BLAS1 - Giunto unione per scatole di derivazione da incasso: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36<\/title>\n<meta name=\"description\" content=\"Giunto d&#039;unione o dispositivo di accoppiamento, che consente di mantenere alla giusta distanza le scatole durante le operazioni di muratura, per scatole di derivazione multifunzione: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BLAS1 - Giunto unione per scatole di derivazione da incasso: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36\" \/>\n<meta property=\"og:description\" content=\"Giunto d&#039;unione o dispositivo di accoppiamento, che consente di mantenere alla giusta distanza le scatole durante le operazioni di muratura, per scatole di derivazione multifunzione: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/\" \/>\n<meta property=\"og:site_name\" content=\"AVE S.p.A.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aveinterruttori\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T03:32:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005323.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@aveinterruttori\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/\",\"url\":\"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/\",\"name\":\"BLAS1 - Giunto unione per scatole di derivazione da incasso: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36\",\"isPartOf\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005323.jpg\",\"datePublished\":\"2019-12-09T13:21:13+00:00\",\"dateModified\":\"2026-05-13T03:32:04+00:00\",\"description\":\"Giunto d&#39;unione o dispositivo di accoppiamento, che consente di mantenere alla giusta distanza le scatole durante le operazioni di muratura, per scatole di derivazione multifunzione: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/#primaryimage\",\"url\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005323.jpg\",\"contentUrl\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005323.jpg\",\"width\":1300,\"height\":1300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Catalogo tecnico\",\"item\":\"https:\/\/www.ave.it\/catalog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\/\/www.ave.it\/catalog\/home\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Scatole, Contenitori e Centralini\",\"item\":\"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/scatole-contenitori-e-centralini\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Scatole da incasso per serie civili\",\"item\":\"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/scatole-contenitori-e-centralini\/scatole-da-incasso-per-serie-civili\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Accessori per scatole per pareti in muratura\",\"item\":\"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/scatole-contenitori-e-centralini\/scatole-da-incasso-per-serie-civili\/accessori-per-scatole-per-pareti-in-muratura\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"BLAS1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ave.it\/catalog\/#website\",\"url\":\"https:\/\/www.ave.it\/catalog\/\",\"name\":\"AVE S.p.A.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ave.it\/catalog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ave.it\/catalog\/#organization\",\"name\":\"Ave S.p.A.\",\"url\":\"https:\/\/www.ave.it\/catalog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png\",\"contentUrl\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png\",\"width\":330,\"height\":142,\"caption\":\"Ave S.p.A.\"},\"image\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/aveinterruttori\/\",\"https:\/\/x.com\/aveinterruttori\",\"https:\/\/www.instagram.com\/aveinterruttori\/\",\"https:\/\/www.linkedin.com\/company\/ave-spa\/\",\"https:\/\/www.youtube.com\/user\/DominaPlusAve\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BLAS1 - Giunto unione per scatole di derivazione da incasso: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36","description":"Giunto d&#39;unione o dispositivo di accoppiamento, che consente di mantenere alla giusta distanza le scatole durante le operazioni di muratura, per scatole di derivazione multifunzione: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/","og_locale":"it_IT","og_type":"article","og_title":"BLAS1 - Giunto unione per scatole di derivazione da incasso: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36","og_description":"Giunto d&#39;unione o dispositivo di accoppiamento, che consente di mantenere alla giusta distanza le scatole durante le operazioni di muratura, per scatole di derivazione multifunzione: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36","og_url":"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/","og_site_name":"AVE S.p.A.","article_publisher":"https:\/\/www.facebook.com\/aveinterruttori\/","article_modified_time":"2026-05-13T03:32:04+00:00","og_image":[{"width":1300,"height":1300,"url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005323.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@aveinterruttori","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/","url":"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/","name":"BLAS1 - Giunto unione per scatole di derivazione da incasso: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36","isPartOf":{"@id":"https:\/\/www.ave.it\/catalog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/#primaryimage"},"image":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005323.jpg","datePublished":"2019-12-09T13:21:13+00:00","dateModified":"2026-05-13T03:32:04+00:00","description":"Giunto d&#39;unione o dispositivo di accoppiamento, che consente di mantenere alla giusta distanza le scatole durante le operazioni di muratura, per scatole di derivazione multifunzione: BL01P, BL05P, BL06P, BL07P, BL08P, BL08LP, BL09P, BL10S, BL18S e 53S36","breadcrumb":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/#primaryimage","url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005323.jpg","contentUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005323.jpg","width":1300,"height":1300},{"@type":"BreadcrumbList","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/blas1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Catalogo tecnico","item":"https:\/\/www.ave.it\/catalog\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ave.it\/catalog\/home\/"},{"@type":"ListItem","position":3,"name":"Scatole, Contenitori e Centralini","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/scatole-contenitori-e-centralini\/"},{"@type":"ListItem","position":4,"name":"Scatole da incasso per serie civili","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/scatole-contenitori-e-centralini\/scatole-da-incasso-per-serie-civili\/"},{"@type":"ListItem","position":5,"name":"Accessori per scatole per pareti in muratura","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/scatole-contenitori-e-centralini\/scatole-da-incasso-per-serie-civili\/accessori-per-scatole-per-pareti-in-muratura\/"},{"@type":"ListItem","position":6,"name":"BLAS1"}]},{"@type":"WebSite","@id":"https:\/\/www.ave.it\/catalog\/#website","url":"https:\/\/www.ave.it\/catalog\/","name":"AVE S.p.A.","description":"","publisher":{"@id":"https:\/\/www.ave.it\/catalog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ave.it\/catalog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.ave.it\/catalog\/#organization","name":"Ave S.p.A.","url":"https:\/\/www.ave.it\/catalog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/","url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png","contentUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png","width":330,"height":142,"caption":"Ave S.p.A."},"image":{"@id":"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aveinterruttori\/","https:\/\/x.com\/aveinterruttori","https:\/\/www.instagram.com\/aveinterruttori\/","https:\/\/www.linkedin.com\/company\/ave-spa\/","https:\/\/www.youtube.com\/user\/DominaPlusAve"]}]}},"lang":"it","translations":{"it":40237,"en":81703},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/40237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":28,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/40237\/revisions"}],"predecessor-version":[{"id":456618,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/40237\/revisions\/456618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/media\/251421"}],"wp:attachment":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/media?parent=40237"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_brand?post=40237"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_cat?post=40237"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_tag?post=40237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}