{"id":40311,"date":"2019-12-09T14:21:38","date_gmt":"2019-12-09T13:21:38","guid":{"rendered":"https:\/\/www.ave.it\/prodotto\/bl08lcgc\/"},"modified":"2026-05-13T05:29:04","modified_gmt":"2026-05-13T03:29:04","slug":"bl08lcgc","status":"publish","type":"product","link":"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/","title":{"rendered":"BL08LCGC"},"content":{"rendered":"<p>{&#8220;Prezzo&#8221;:{&#8220;Prezzo&#8221;:&#8221;19,17&#8243;},&#8221;Descrizione&#8221;:{&#8220;Descrizione&#8221;:&#8221;Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\\\/o tramezze leggere&#8221;,&#8221;Descrizione estesa&#8221;:&#8221;Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\\\/o tramezze leggere, possibilit&#224;  di sostituire il coperchio in dotazione con la versione IP55 codice BLST08L. Dimensioni (L H P): 398 x 224 x 75 mm&#8221;},&#8221;Dati commerciali&#8221;:{&#8220;Codice EAN13&#8243;:&#8221;8008379094349&#8243;,&#8221;Imballo standard&#8221;:&#8221;12,00&#8243;,&#8221;Codice EAN13 imb. std.&#8221;:&#8221;8008379235568&#8243;,&#8221;Lunghezza imb. std.&#8221;:&#8221;585,00&#8243;,&#8221;Larghezza imb. std.&#8221;:&#8221;385,00&#8243;,&#8221;Altezza imb. std.&#8221;:&#8221;480,00&#8243;,&#8221;Volume imb. std.&#8221;:&#8221;108,10&#8243;,&#8221;Peso imb. std.&#8221;:&#8221;7170,00&#8243;,&#8221;Imballo minimo&#8221;:&#8221;1,00&#8243;,&#8221;Codice EAN13 imb.min.&#8221;:&#8221;8008379094349&#8243;,&#8221;Lunghezza imb. min.&#8221;:&#8221;255,46&#8243;,&#8221;Larghezza imb. min.&#8221;:&#8221;168,12&#8243;,&#8221;Altezza imb. min.&#8221;:&#8221;209,61&#8243;,&#8221;Volume imb. min.&#8221;:&#8221;9,00&#8243;,&#8221;Peso imb. min.&#8221;:&#8221;520,00&#8243;,&#8221;Quantit\\u00e0 min. ordine&#8221;:&#8221;12,00&#8243;,&#8221;Riferimento Metel&#8221;:&#8221;SCATOLA DERIV.+ COPERCHIO IP40&#8243;,&#8221;Stato prodotto&#8221;:&#8221;A Magazzino&#8221;},&#8221;Categorizzazione&#8221;:{&#8220;Serie&#8221;:&#8221;406&#8243;,&#8221;Divisione&#8221;:&#8221;4&#8243;,&#8221;GP&#8221;:&#8221;46&#8243;,&#8221;Classe&#8221;:&#8221;EC002601&#8243;},&#8221;Marchi senza file&#8221;:{&#8220;I.M.Q.&#8221;:&#8221;I.M.Q.&#8221;},&#8221;Dati tecnici ETIM&#8221;:{&#8220;Tipo di montaggio&#8221;:&#8221;Incassato&#8221;,&#8221;Colore&#8221;:&#8221;Blu&#8221;,&#8221;Larghezza&#8221;:&#8221;398 Millimetro&#8221;,&#8221;Tipologia&#8221;:&#8221;Altro&#8221;,&#8221;Forma&#8221;:&#8221;Rettangolare&#8221;,&#8221;Protezione della superficie&#8221;:&#8221;Non trattato&#8221;,&#8221;Diametro&#8221;:&#8221;0 Millimetro&#8221;,&#8221;Attrezzatura&#8221;:&#8221;Altro&#8221;,&#8221;Tipologia costruttiva&#8221;:&#8221;Cassetta portafrutti&#8221;,&#8221;Profondit\\u00e0 interna&#8221;:&#8221;- Millimetro&#8221;,&#8221;Accoppiabile&#8221;:&#8221;No&#8221;,&#8221;Lunghezza&#8221;:&#8221;224 Millimetro&#8221;,&#8221;Piombabile&#8221;:&#8221;No&#8221;,&#8221;Integrit\\u00e0 del circuito&#8221;:&#8221;Senza&#8221;,&#8221;Materiale&#8221;:&#8221;Plastica&#8221;,&#8221;Fissaggio degli apparecchi&#8221;:&#8221;Avvitare&#8221;,&#8221;Fissaggio del coperchio&#8221;:&#8221;Altro&#8221;,&#8221;Fissaggio del gancio portalampada&#8221;:&#8221;No&#8221;,&#8221;Sezione max. del conduttore&#8221;:&#8221;- Millimetro quadrato&#8221;,&#8221;Con schermatura&#8221;:&#8221;No&#8221;,&#8221;Con viti&#8221;:&#8221;No&#8221;,&#8221;Ermetico al vento&#8221;:&#8221;No&#8221;,&#8221;Profondit\\u00e0&#8243;:&#8221;75|75 Millimetro&#8221;,&#8221;Per diametro cavo&#8221;:&#8221;- Millimetro&#8221;,&#8221;Grado di protezione (IP)&#8221;:&#8221;IP40&#8243;,&#8221;Per diametro del tubo&#8221;:&#8221;&#8221;,&#8221;Inserimento dal retro&#8221;:&#8221;Si&#8221;,&#8221;Bloccaggio del tubo&#8221;:&#8221;No&#8221;,&#8221;Applicazione speciale&#8221;:&#8221;Altro&#8221;,&#8221;Morsetto fissato in posizione&#8221;:&#8221;No&#8221;,&#8221;Con parete divisoria&#8221;:&#8221;No&#8221;,&#8221;Numero di poli del morsetto&#8221;:&#8221;&#8221;,&#8221;Raccordo&#8221;:&#8221;Altro&#8221;,&#8221;Equipaggiato di anello girevole&#8221;:&#8221;No&#8221;,&#8221;Passaggio scatola tramite membrana di tenuta&#8221;:&#8221;No&#8221;,&#8221;Passaggio scatola tramite raccordi per tubo&#8221;:&#8221;No&#8221;,&#8221;Passaggio scatola tramite membrana graduata&#8221;:&#8221;No&#8221;,&#8221;Bloccaggio tubo opzionale&#8221;:&#8221;Si&#8221;,&#8221;Numero di manicotti in dotazione&#8221;:&#8221;&#8221;,&#8221;Esecuzione coperchio&#8221;:&#8221;Altro&#8221;,&#8221;Passaggio scatola tramite foro sfondabile&#8221;:&#8221;Si&#8221;,&#8221;Coperchio trasparente&#8221;:&#8221;No&#8221;,&#8221;Tipo di protezione (NEMA)&#8221;:&#8221;Altro&#8221;,&#8221;Adatto per pareti \\\/ pannelli di spessore&#8221;:&#8221;- Millimetro&#8221;,&#8221;Numero di alette di fissaggio dell&#8217;apparecchio non&#8221;:&#8221;&#8221;,&#8221;Numero di alette di fissaggio dell&#8217;apparecchio reg&#8221;:&#8221;&#8221;},&#8221;Ingombro (DXF)&#8221;:{&#8220;INGOMBRO BL08LCGC SMONTATO&#8221;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/0000005781.dxf&#8221;,&#8221;BL08LCGC&#8221;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/A000005307.dxf&#8221;,&#8221;INGOMBRO BL08LCGC&#8221;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/0000005780.dxf&#8221;},&#8221;Pagina Catalogo Commerciale&#8221;:{&#8220;Pagina catalogo Pag363&#8243;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/D000000240.pdf&#8221;},&#8221;Immagini Articolo&#8221;:{&#8220;BL08LCGC&#8221;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/A000005308.jpg&#8221;},&#8221;Ingombro (PNG)&#8221;:{&#8220;BL08LCGC&#8221;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/E000000854.png&#8221;},&#8221;Data ultimo aggiornamento&#8221;:{&#8220;Data ultimo aggiornamento&#8221;:&#8221;02-03-2026&#8243;}}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\/o tramezze leggere, possibilit&#224;  di sostituire il coperchio in dotazione con la versione IP55 codice BLST08L. Dimensioni (L H P): 398 x 224 x 75 mm<\/p>\n","protected":false},"featured_media":246320,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3624,3635,3650],"product_tag":[3651],"class_list":{"0":"post-40311","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-scatole-contenitori-e-centralini","7":"product_cat-scatole-derivazione-multif-incasso","8":"product_cat-scatole-di-derivazione-multifunzione-per-pareti-in-cartongesso","9":"product_tag-scatole-di-derivazione-multifunzione-per-pareti-in-cartongesso","11":"first","12":"instock","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BL08LCGC - Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\/o tramezze leggere<\/title>\n<meta name=\"description\" content=\"Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\/o tramezze leggere, possibilit&#224; di sostituire il coperchio in dotazione con la versione IP55 codice BLST08L. Dimensioni (L H P): 398 x 224 x 75 mm\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BL08LCGC - Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\/o tramezze leggere\" \/>\n<meta property=\"og:description\" content=\"Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\/o tramezze leggere, possibilit&#224; di sostituire il coperchio in dotazione con la versione IP55 codice BLST08L. Dimensioni (L H P): 398 x 224 x 75 mm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/\" \/>\n<meta property=\"og:site_name\" content=\"AVE S.p.A.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aveinterruttori\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T03:29:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005308.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@aveinterruttori\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/\",\"url\":\"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/\",\"name\":\"BL08LCGC - Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\/o tramezze leggere\",\"isPartOf\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005308.jpg\",\"datePublished\":\"2019-12-09T13:21:38+00:00\",\"dateModified\":\"2026-05-13T03:29:04+00:00\",\"description\":\"Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\/o tramezze leggere, possibilit&#224; di sostituire il coperchio in dotazione con la versione IP55 codice BLST08L. Dimensioni (L H P): 398 x 224 x 75 mm\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/#primaryimage\",\"url\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005308.jpg\",\"contentUrl\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005308.jpg\",\"width\":250,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Catalogo tecnico\",\"item\":\"https:\/\/www.ave.it\/catalog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\/\/www.ave.it\/catalog\/home\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Scatole, Contenitori e Centralini\",\"item\":\"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/scatole-contenitori-e-centralini\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Scatole Derivazione Multif. Incasso\",\"item\":\"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/scatole-contenitori-e-centralini\/scatole-derivazione-multif-incasso\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Scatole di derivazione multifunzione per pareti in cartongesso\",\"item\":\"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/scatole-contenitori-e-centralini\/scatole-derivazione-multif-incasso\/scatole-di-derivazione-multifunzione-per-pareti-in-cartongesso\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"BL08LCGC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ave.it\/catalog\/#website\",\"url\":\"https:\/\/www.ave.it\/catalog\/\",\"name\":\"AVE S.p.A.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ave.it\/catalog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ave.it\/catalog\/#organization\",\"name\":\"Ave S.p.A.\",\"url\":\"https:\/\/www.ave.it\/catalog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png\",\"contentUrl\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png\",\"width\":330,\"height\":142,\"caption\":\"Ave S.p.A.\"},\"image\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/aveinterruttori\/\",\"https:\/\/x.com\/aveinterruttori\",\"https:\/\/www.instagram.com\/aveinterruttori\/\",\"https:\/\/www.linkedin.com\/company\/ave-spa\/\",\"https:\/\/www.youtube.com\/user\/DominaPlusAve\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BL08LCGC - Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\/o tramezze leggere","description":"Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\/o tramezze leggere, possibilit&#224; di sostituire il coperchio in dotazione con la versione IP55 codice BLST08L. Dimensioni (L H P): 398 x 224 x 75 mm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/","og_locale":"it_IT","og_type":"article","og_title":"BL08LCGC - Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\/o tramezze leggere","og_description":"Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\/o tramezze leggere, possibilit&#224; di sostituire il coperchio in dotazione con la versione IP55 codice BLST08L. Dimensioni (L H P): 398 x 224 x 75 mm","og_url":"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/","og_site_name":"AVE S.p.A.","article_publisher":"https:\/\/www.facebook.com\/aveinterruttori\/","article_modified_time":"2026-05-13T03:29:04+00:00","og_image":[{"width":250,"height":250,"url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005308.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@aveinterruttori","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/","url":"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/","name":"BL08LCGC - Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\/o tramezze leggere","isPartOf":{"@id":"https:\/\/www.ave.it\/catalog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/#primaryimage"},"image":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005308.jpg","datePublished":"2019-12-09T13:21:38+00:00","dateModified":"2026-05-13T03:29:04+00:00","description":"Scatola da incasso di derivazione completa di coperchio IP40 per pareti in cartongesso e\/o tramezze leggere, possibilit&#224; di sostituire il coperchio in dotazione con la versione IP55 codice BLST08L. Dimensioni (L H P): 398 x 224 x 75 mm","breadcrumb":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/#primaryimage","url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005308.jpg","contentUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000005308.jpg","width":250,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/bl08lcgc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Catalogo tecnico","item":"https:\/\/www.ave.it\/catalog\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ave.it\/catalog\/home\/"},{"@type":"ListItem","position":3,"name":"Scatole, Contenitori e Centralini","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/scatole-contenitori-e-centralini\/"},{"@type":"ListItem","position":4,"name":"Scatole Derivazione Multif. Incasso","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/scatole-contenitori-e-centralini\/scatole-derivazione-multif-incasso\/"},{"@type":"ListItem","position":5,"name":"Scatole di derivazione multifunzione per pareti in cartongesso","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/scatole-contenitori-e-centralini\/scatole-derivazione-multif-incasso\/scatole-di-derivazione-multifunzione-per-pareti-in-cartongesso\/"},{"@type":"ListItem","position":6,"name":"BL08LCGC"}]},{"@type":"WebSite","@id":"https:\/\/www.ave.it\/catalog\/#website","url":"https:\/\/www.ave.it\/catalog\/","name":"AVE S.p.A.","description":"","publisher":{"@id":"https:\/\/www.ave.it\/catalog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ave.it\/catalog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.ave.it\/catalog\/#organization","name":"Ave S.p.A.","url":"https:\/\/www.ave.it\/catalog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/","url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png","contentUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png","width":330,"height":142,"caption":"Ave S.p.A."},"image":{"@id":"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aveinterruttori\/","https:\/\/x.com\/aveinterruttori","https:\/\/www.instagram.com\/aveinterruttori\/","https:\/\/www.linkedin.com\/company\/ave-spa\/","https:\/\/www.youtube.com\/user\/DominaPlusAve"]}]}},"lang":"it","translations":{"it":40311,"en":82748},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/40311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":37,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/40311\/revisions"}],"predecessor-version":[{"id":456586,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/40311\/revisions\/456586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/media\/246320"}],"wp:attachment":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/media?parent=40311"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_brand?post=40311"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_cat?post=40311"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_tag?post=40311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}