{"id":42260,"date":"2019-12-09T14:40:05","date_gmt":"2019-12-09T13:40:05","guid":{"rendered":"https:\/\/www.ave.it\/prodotto\/44ple03noc\/"},"modified":"2026-05-13T02:37:03","modified_gmt":"2026-05-13T00:37:03","slug":"44ple03noc","status":"publish","type":"product","link":"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/","title":{"rendered":"44PLE03NOC"},"content":{"rendered":"<p>{&#8220;Prezzo&#8221;:{&#8220;Prezzo&#8221;:&#8221;111,91&#8243;},&#8221;Descrizione&#8221;:{&#8220;Descrizione&#8221;:&#8221;Placca England Style S44, in legno colore noce &#8211; 3 comandi a levetta &#8211; 3 Mod.&#8221;,&#8221;Descrizione estesa&#8221;:&#8221;Placca serie ENGLAND STYLE 44 in LEGNO per scatola rettangolare &#8211; colore Noce &#8211; 3 comandi a levetta &#8211; supporto da utilizzare 44A03 &#8211; dimensioni 124 x 88 mm&#8221;},&#8221;Dati commerciali&#8221;:{&#8220;Codice EAN13&#8243;:&#8221;8008379110001&#8243;,&#8221;Imballo standard&#8221;:&#8221;1,00&#8243;,&#8221;Imballo minimo&#8221;:&#8221;1,00&#8243;,&#8221;Codice EAN13 imb.min.&#8221;:&#8221;8008379110001&#8243;,&#8221;Lunghezza imb. min.&#8221;:&#8221;132,00&#8243;,&#8221;Larghezza imb. min.&#8221;:&#8221;169,00&#8243;,&#8221;Altezza imb. min.&#8221;:&#8221;18,20&#8243;,&#8221;Volume imb. min.&#8221;:&#8221;0,40&#8243;,&#8221;Peso imb. min.&#8221;:&#8221;141,00&#8243;,&#8221;Quantit\\u00e0 min. ordine&#8221;:&#8221;1,00&#8243;,&#8221;Riferimento Metel&#8221;:&#8221;PLACCA ENGLAND STYLE LEGNO NOC.3COM&#8221;,&#8221;Stato prodotto&#8221;:&#8221;A Magazzino&#8221;},&#8221;Categorizzazione&#8221;:{&#8220;Serie&#8221;:&#8221;129&#8243;,&#8221;Divisione&#8221;:&#8221;1&#8243;,&#8221;GP&#8221;:&#8221;73&#8243;,&#8221;Classe&#8221;:&#8221;EC000007&#8243;},&#8221;Marchi senza file&#8221;:{&#8220;I.M.Q.&#8221;:&#8221;I.M.Q.&#8221;},&#8221;Dati tecnici ETIM&#8221;:{&#8220;Colore&#8221;:&#8221;Legno&#8221;,&#8221;Larghezza&#8221;:&#8221;124 Millimetro&#8221;,&#8221;Altezza&#8221;:&#8221;88 Millimetro&#8221;,&#8221;Profondit\\u00e0&#8243;:&#8221;8,1 Millimetro&#8221;,&#8221;Numero di unit\\u00e0&#8243;:&#8221;3&#8243;,&#8221;Con coperchio a cerniera&#8221;:&#8221;No&#8221;,&#8221;Protezione della superficie&#8221;:&#8221;Non trattato&#8221;,&#8221;Altezza della parte incassata&#8221;:&#8221;- Millimetro&#8221;,&#8221;Larghezza di montaggio&#8221;:&#8221;- Millimetro&#8221;,&#8221;Casella di testo\\\/superficie di marcatura&#8221;:&#8221;No&#8221;,&#8221;Qualit\\u00e0 del materiale&#8221;:&#8221;Altro&#8221;,&#8221;Materiale&#8221;:&#8221;Legno&#8221;,&#8221;Tipo di fissaggio&#8221;:&#8221;Bloccare in posizione&#8221;,&#8221;Direzione di montaggio&#8221;:&#8221;Orizzontale&#8221;,&#8221;Resistenza agli urti&#8221;:&#8221;Altro&#8221;,&#8221;Grado di protezione (IP)&#8221;:&#8221;Altro&#8221;,&#8221;Adatto per scatola di canale sotterraneo&#8221;:&#8221;No&#8221;,&#8221;Trasparente&#8221;:&#8221;No&#8221;,&#8221;Tipo superficie&#8221;:&#8221;Opaco&#8221;,&#8221;Adatto per canale da incasso per apparecchi&#8221;:&#8221;No&#8221;,&#8221;Adatto per installazione ad incasso&#8221;:&#8221;No&#8221;,&#8221;Montaggio a incasso&#8221;:&#8221;No&#8221;,&#8221;Numero di unit\\u00e0 orizzontali&#8221;:&#8221;3&#8243;,&#8221;Numero di unit\\u00e0 verticali&#8221;:&#8221;1&#8243;,&#8221;Diametro del foro (apertura)&#8221;:&#8221;0 Millimetro&#8221;,&#8221;Numero dei moduli in orizzontale (per costruzione&#8221;:&#8221;3&#8243;,&#8221;Numero dei moduli in verticale (per costruzione mo&#8221;:&#8221;1&#8243;,&#8221;Con cornice di montaggio&#8221;:&#8221;Si&#8221;,&#8221;Trattamento antibatterico&#8221;:&#8221;No&#8221;},&#8221;Pagina Catalogo Commerciale&#8221;:{&#8220;Pagina catalogo Pag202&#8243;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/D000000137.pdf&#8221;},&#8221;Immagini Articolo&#8221;:{&#8220;44PLE03NOC&#8221;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/A000002362.jpg&#8221;},&#8221;Data ultimo aggiornamento&#8221;:{&#8220;Data ultimo aggiornamento&#8221;:&#8221;02-03-2026&#8243;}}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Placca serie ENGLAND STYLE 44 in LEGNO per scatola rettangolare &#8211; colore Noce &#8211; 3 comandi a levetta &#8211; supporto da utilizzare 44A03 &#8211; dimensioni 124 x 88 mm<\/p>\n","protected":false},"featured_media":248446,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3602,3892,3893,3952],"product_tag":[3953],"class_list":{"0":"post-42260","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-serie-civili-componibili","7":"product_cat-soluzioni-new-style-england-style-44","8":"product_cat-placche-soluzioni-new-style-england-style-44","9":"product_cat-placche-in-legno-england-style","10":"product_tag-placche-in-legno-england-style","12":"first","13":"instock","14":"purchasable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>44PLE03NOC - Placca England Style S44, in legno colore noce - 3 comandi a levetta - 3 Mod.<\/title>\n<meta name=\"description\" content=\"Placca serie ENGLAND STYLE 44 in LEGNO per scatola rettangolare - colore Noce - 3 comandi a levetta - supporto da utilizzare 44A03 - dimensioni 124 x 88 mm\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"44PLE03NOC - Placca England Style S44, in legno colore noce - 3 comandi a levetta - 3 Mod.\" \/>\n<meta property=\"og:description\" content=\"Placca serie ENGLAND STYLE 44 in LEGNO per scatola rettangolare - colore Noce - 3 comandi a levetta - supporto da utilizzare 44A03 - dimensioni 124 x 88 mm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/\" \/>\n<meta property=\"og:site_name\" content=\"AVE S.p.A.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aveinterruttori\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T00:37:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000002362.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@aveinterruttori\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/\",\"url\":\"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/\",\"name\":\"44PLE03NOC - Placca England Style S44, in legno colore noce - 3 comandi a levetta - 3 Mod.\",\"isPartOf\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000002362.jpg\",\"datePublished\":\"2019-12-09T13:40:05+00:00\",\"dateModified\":\"2026-05-13T00:37:03+00:00\",\"description\":\"Placca serie ENGLAND STYLE 44 in LEGNO per scatola rettangolare - colore Noce - 3 comandi a levetta - supporto da utilizzare 44A03 - dimensioni 124 x 88 mm\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/#primaryimage\",\"url\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000002362.jpg\",\"contentUrl\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000002362.jpg\",\"width\":1300,\"height\":1300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Catalogo tecnico\",\"item\":\"https:\/\/www.ave.it\/catalog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\/\/www.ave.it\/catalog\/home\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Serie civili componibili\",\"item\":\"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/serie-civili-componibili\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Soluzioni New Style\/England Style 44\",\"item\":\"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/serie-civili-componibili\/soluzioni-new-style-england-style-44\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Placche\",\"item\":\"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/serie-civili-componibili\/soluzioni-new-style-england-style-44\/placche-soluzioni-new-style-england-style-44\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Placche in Legno (England style)\",\"item\":\"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/serie-civili-componibili\/soluzioni-new-style-england-style-44\/placche-soluzioni-new-style-england-style-44\/placche-in-legno-england-style\/\"},{\"@type\":\"ListItem\",\"position\":7,\"name\":\"44PLE03NOC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ave.it\/catalog\/#website\",\"url\":\"https:\/\/www.ave.it\/catalog\/\",\"name\":\"AVE S.p.A.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ave.it\/catalog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ave.it\/catalog\/#organization\",\"name\":\"Ave S.p.A.\",\"url\":\"https:\/\/www.ave.it\/catalog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png\",\"contentUrl\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png\",\"width\":330,\"height\":142,\"caption\":\"Ave S.p.A.\"},\"image\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/aveinterruttori\/\",\"https:\/\/x.com\/aveinterruttori\",\"https:\/\/www.instagram.com\/aveinterruttori\/\",\"https:\/\/www.linkedin.com\/company\/ave-spa\/\",\"https:\/\/www.youtube.com\/user\/DominaPlusAve\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"44PLE03NOC - Placca England Style S44, in legno colore noce - 3 comandi a levetta - 3 Mod.","description":"Placca serie ENGLAND STYLE 44 in LEGNO per scatola rettangolare - colore Noce - 3 comandi a levetta - supporto da utilizzare 44A03 - dimensioni 124 x 88 mm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/","og_locale":"it_IT","og_type":"article","og_title":"44PLE03NOC - Placca England Style S44, in legno colore noce - 3 comandi a levetta - 3 Mod.","og_description":"Placca serie ENGLAND STYLE 44 in LEGNO per scatola rettangolare - colore Noce - 3 comandi a levetta - supporto da utilizzare 44A03 - dimensioni 124 x 88 mm","og_url":"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/","og_site_name":"AVE S.p.A.","article_publisher":"https:\/\/www.facebook.com\/aveinterruttori\/","article_modified_time":"2026-05-13T00:37:03+00:00","og_image":[{"width":1300,"height":1300,"url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000002362.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@aveinterruttori","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/","url":"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/","name":"44PLE03NOC - Placca England Style S44, in legno colore noce - 3 comandi a levetta - 3 Mod.","isPartOf":{"@id":"https:\/\/www.ave.it\/catalog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/#primaryimage"},"image":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000002362.jpg","datePublished":"2019-12-09T13:40:05+00:00","dateModified":"2026-05-13T00:37:03+00:00","description":"Placca serie ENGLAND STYLE 44 in LEGNO per scatola rettangolare - colore Noce - 3 comandi a levetta - supporto da utilizzare 44A03 - dimensioni 124 x 88 mm","breadcrumb":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/#primaryimage","url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000002362.jpg","contentUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000002362.jpg","width":1300,"height":1300},{"@type":"BreadcrumbList","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/44ple03noc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Catalogo tecnico","item":"https:\/\/www.ave.it\/catalog\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ave.it\/catalog\/home\/"},{"@type":"ListItem","position":3,"name":"Serie civili componibili","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/serie-civili-componibili\/"},{"@type":"ListItem","position":4,"name":"Soluzioni New Style\/England Style 44","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/serie-civili-componibili\/soluzioni-new-style-england-style-44\/"},{"@type":"ListItem","position":5,"name":"Placche","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/serie-civili-componibili\/soluzioni-new-style-england-style-44\/placche-soluzioni-new-style-england-style-44\/"},{"@type":"ListItem","position":6,"name":"Placche in Legno (England style)","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/serie-civili-componibili\/soluzioni-new-style-england-style-44\/placche-soluzioni-new-style-england-style-44\/placche-in-legno-england-style\/"},{"@type":"ListItem","position":7,"name":"44PLE03NOC"}]},{"@type":"WebSite","@id":"https:\/\/www.ave.it\/catalog\/#website","url":"https:\/\/www.ave.it\/catalog\/","name":"AVE S.p.A.","description":"","publisher":{"@id":"https:\/\/www.ave.it\/catalog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ave.it\/catalog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.ave.it\/catalog\/#organization","name":"Ave S.p.A.","url":"https:\/\/www.ave.it\/catalog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/","url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png","contentUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png","width":330,"height":142,"caption":"Ave S.p.A."},"image":{"@id":"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aveinterruttori\/","https:\/\/x.com\/aveinterruttori","https:\/\/www.instagram.com\/aveinterruttori\/","https:\/\/www.linkedin.com\/company\/ave-spa\/","https:\/\/www.youtube.com\/user\/DominaPlusAve"]}]}},"lang":"it","translations":{"it":42260,"en":81330},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/42260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":42,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/42260\/revisions"}],"predecessor-version":[{"id":454848,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/42260\/revisions\/454848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/media\/248446"}],"wp:attachment":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/media?parent=42260"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_brand?post=42260"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_cat?post=42260"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_tag?post=42260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}