{"id":44543,"date":"2019-12-09T14:52:45","date_gmt":"2019-12-09T13:52:45","guid":{"rendered":"https:\/\/www.ave.it\/prodotto\/45p002bg\/"},"modified":"2026-07-15T04:17:02","modified_gmt":"2026-07-15T02:17:02","slug":"45p002bg","status":"publish","type":"product","link":"https:\/\/www.ave.it\/catalog\/prodotto\/45p002bg\/","title":{"rendered":"45P002BG"},"content":{"rendered":"<p>{&#8220;Prezzo&#8221;:{&#8220;Prezzo&#8221;:&#8221;3,59&#8243;},&#8221;Descrizione&#8221;:{&#8220;Descrizione&#8221;:&#8221;Placca lucida in tecnopolimero colore bianco banquise 2 Mod. separati&#8221;,&#8221;Descrizione estesa&#8221;:&#8221;Placche in tecnopolimero  Ral 45  lucida per scatola rettangolare colore Bianco Banquise (RAL 9016) &#8211; 2 (1+1) moduli&#8221;},&#8221;Dati commerciali&#8221;:{&#8220;Codice EAN13&#8243;:&#8221;8008379024155&#8243;,&#8221;Imballo standard&#8221;:&#8221;25,00&#8243;,&#8221;Codice EAN13 imb. std.&#8221;:&#8221;8008379208340&#8243;,&#8221;Lunghezza imb. std.&#8221;:&#8221;220,00&#8243;,&#8221;Larghezza imb. std.&#8221;:&#8221;155,00&#8243;,&#8221;Altezza imb. std.&#8221;:&#8221;90,00&#8243;,&#8221;Volume imb. std.&#8221;:&#8221;3,06&#8243;,&#8221;Peso imb. std.&#8221;:&#8221;513,00&#8243;,&#8221;Imballo minimo&#8221;:&#8221;1,00&#8243;,&#8221;Codice EAN13 imb.min.&#8221;:&#8221;8008379024155&#8243;,&#8221;Lunghezza imb. min.&#8221;:&#8221;75,34&#8243;,&#8221;Larghezza imb. min.&#8221;:&#8221;53,08&#8243;,&#8221;Altezza imb. min.&#8221;:&#8221;30,82&#8243;,&#8221;Volume imb. min.&#8221;:&#8221;0,12&#8243;,&#8221;Peso imb. min.&#8221;:&#8221;18,00&#8243;,&#8221;Quantit\\u00e0 min. ordine&#8221;:&#8221;1,00&#8243;,&#8221;Riferimento Metel&#8221;:&#8221;PLACCA RAL45 LUC 2M. COLOR BANQUISE&#8221;,&#8221;Stato prodotto&#8221;:&#8221;A Magazzino&#8221;},&#8221;Categorizzazione&#8221;:{&#8220;Serie&#8221;:&#8221;106&#8243;,&#8221;Divisione&#8221;:&#8221;1&#8243;,&#8221;GP&#8221;:&#8221;10&#8243;,&#8221;Classe&#8221;:&#8221;EC000007&#8243;},&#8221;Marchi senza file&#8221;:{&#8220;I.M.Q.&#8221;:&#8221;I.M.Q.&#8221;},&#8221;Dati tecnici ETIM&#8221;:{&#8220;Colore&#8221;:&#8221;Bianco&#8221;,&#8221;Larghezza&#8221;:&#8221;119 Millimetro&#8221;,&#8221;Senza alogeni&#8221;:&#8221;No&#8221;,&#8221;Altezza&#8221;:&#8221;80 Millimetro&#8221;,&#8221;Profondit\\u00e0&#8243;:&#8221;8 Millimetro&#8221;,&#8221;Numero di unit\\u00e0&#8243;:&#8221;3&#8243;,&#8221;Con coperchio a cerniera&#8221;:&#8221;No&#8221;,&#8221;Protezione della superficie&#8221;:&#8221;Non trattato&#8221;,&#8221;Altezza della parte incassata&#8221;:&#8221;- Millimetro&#8221;,&#8221;Larghezza di montaggio&#8221;:&#8221;- Millimetro&#8221;,&#8221;Casella di testo\\\/superficie di marcatura&#8221;:&#8221;No&#8221;,&#8221;Qualit\\u00e0 del materiale&#8221;:&#8221;Materiale termoplastico&#8221;,&#8221;Materiale&#8221;:&#8221;Plastica&#8221;,&#8221;Tipo di fissaggio&#8221;:&#8221;Bloccare in posizione&#8221;,&#8221;Direzione di montaggio&#8221;:&#8221;Orizzontale&#8221;,&#8221;Codice RAL (simile)&#8221;:&#8221;9016&#8243;,&#8221;Resistenza agli urti&#8221;:&#8221;Altro&#8221;,&#8221;Grado di protezione (IP)&#8221;:&#8221;IP00&#8243;,&#8221;Adatto per scatola di canale sotterraneo&#8221;:&#8221;No&#8221;,&#8221;Trasparente&#8221;:&#8221;No&#8221;,&#8221;Tipo superficie&#8221;:&#8221;Lucido&#8221;,&#8221;Adatto per canale da incasso per apparecchi&#8221;:&#8221;No&#8221;,&#8221;Adatto per installazione ad incasso&#8221;:&#8221;Si&#8221;,&#8221;Montaggio a incasso&#8221;:&#8221;No&#8221;,&#8221;Numero di unit\\u00e0 orizzontali&#8221;:&#8221;2&#8243;,&#8221;Numero di unit\\u00e0 verticali&#8221;:&#8221;1&#8243;,&#8221;Diametro del foro (apertura)&#8221;:&#8221;0 Millimetro&#8221;,&#8221;Numero dei moduli in orizzontale (per costruzione&#8221;:&#8221;2&#8243;,&#8221;Numero dei moduli in verticale (per costruzione mo&#8221;:&#8221;1&#8243;,&#8221;Con cornice di montaggio&#8221;:&#8221;Si&#8221;,&#8221;Trattamento antibatterico&#8221;:&#8221;No&#8221;},&#8221;Pagina Catalogo Commerciale&#8221;:{&#8220;Pagina catalogo Pag313&#8243;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/D000000164.pdf&#8221;},&#8221;Immagini Articolo&#8221;:{&#8220;45P002BG&#8221;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/A000003443.jpg&#8221;},&#8221;Data ultimo aggiornamento&#8221;:{&#8220;Data ultimo aggiornamento&#8221;:&#8221;18-06-2026&#8243;}}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Placche in tecnopolimero  Ral 45  lucida per scatola rettangolare colore Bianco Banquise (RAL 9016) &#8211; 2 (1+1) moduli<\/p>\n","protected":false},"featured_media":252311,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4230,3664,3663,4229,3602,4231],"product_tag":[4213],"class_list":{"0":"post-44543","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-in-tecnopolimero-placche-ral-45","7":"product_cat-placche","8":"product_cat-placche-e-armature-s45","9":"product_cat-placche-ral-45","10":"product_cat-serie-civili-componibili","11":"product_cat-versione-a-2-moduli-separati-in-tecnopolimero-placche-ral-45","12":"product_tag-versione-a-2-moduli-separati","14":"first","15":"instock","16":"purchasable","17":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>45P002BG - Placca lucida in tecnopolimero colore bianco banquise 2 Mod. separati<\/title>\n<meta name=\"description\" content=\"Placche in tecnopolimero Ral 45 lucida per scatola rettangolare colore Bianco Banquise (RAL 9016) - 2 (1+1) moduli\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ave.it\/catalog\/prodotto\/45p002bg\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"45P002BG - Placca lucida in tecnopolimero colore bianco banquise 2 Mod. separati\" \/>\n<meta property=\"og:description\" content=\"Placche in tecnopolimero Ral 45 lucida per scatola rettangolare colore Bianco Banquise (RAL 9016) - 2 (1+1) moduli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ave.it\/catalog\/prodotto\/45p002bg\/\" \/>\n<meta property=\"og:site_name\" content=\"AVE S.p.A.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aveinterruttori\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T02:17:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000003443.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@aveinterruttori\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/prodotto\\\/45p002bg\\\/\",\"url\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/prodotto\\\/45p002bg\\\/\",\"name\":\"45P002BG - Placca lucida in tecnopolimero colore bianco banquise 2 Mod. separati\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/prodotto\\\/45p002bg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/prodotto\\\/45p002bg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/a000003443.jpg\",\"datePublished\":\"2019-12-09T13:52:45+00:00\",\"dateModified\":\"2026-07-15T02:17:02+00:00\",\"description\":\"Placche in tecnopolimero Ral 45 lucida per scatola rettangolare colore Bianco Banquise (RAL 9016) - 2 (1+1) moduli\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/prodotto\\\/45p002bg\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ave.it\\\/catalog\\\/prodotto\\\/45p002bg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/prodotto\\\/45p002bg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/a000003443.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/a000003443.jpg\",\"width\":1300,\"height\":1300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/prodotto\\\/45p002bg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Catalogo tecnico\",\"item\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Serie civili componibili\",\"item\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/categoria-prodotto\\\/serie-civili-componibili\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Placche e armature S45\",\"item\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/categoria-prodotto\\\/serie-civili-componibili\\\/placche-e-armature-s45\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Placche\",\"item\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/categoria-prodotto\\\/serie-civili-componibili\\\/placche-e-armature-s45\\\/placche\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Placche Ral 45\",\"item\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/categoria-prodotto\\\/serie-civili-componibili\\\/placche-e-armature-s45\\\/placche\\\/placche-ral-45\\\/\"},{\"@type\":\"ListItem\",\"position\":7,\"name\":\"In tecnopolimero\",\"item\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/categoria-prodotto\\\/serie-civili-componibili\\\/placche-e-armature-s45\\\/placche\\\/placche-ral-45\\\/in-tecnopolimero-placche-ral-45\\\/\"},{\"@type\":\"ListItem\",\"position\":8,\"name\":\"Versione a 2 moduli separati\",\"item\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/categoria-prodotto\\\/serie-civili-componibili\\\/placche-e-armature-s45\\\/placche\\\/placche-ral-45\\\/in-tecnopolimero-placche-ral-45\\\/versione-a-2-moduli-separati-in-tecnopolimero-placche-ral-45\\\/\"},{\"@type\":\"ListItem\",\"position\":9,\"name\":\"45P002BG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/#website\",\"url\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/\",\"name\":\"AVE S.p.A.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/#organization\",\"name\":\"Ave S.p.A.\",\"url\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-ave.png\",\"contentUrl\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-ave.png\",\"width\":330,\"height\":142,\"caption\":\"Ave S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ave.it\\\/catalog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aveinterruttori\\\/\",\"https:\\\/\\\/x.com\\\/aveinterruttori\",\"https:\\\/\\\/www.instagram.com\\\/aveinterruttori\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ave-spa\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/DominaPlusAve\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"45P002BG - Placca lucida in tecnopolimero colore bianco banquise 2 Mod. separati","description":"Placche in tecnopolimero Ral 45 lucida per scatola rettangolare colore Bianco Banquise (RAL 9016) - 2 (1+1) moduli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ave.it\/catalog\/prodotto\/45p002bg\/","og_locale":"it_IT","og_type":"article","og_title":"45P002BG - Placca lucida in tecnopolimero colore bianco banquise 2 Mod. separati","og_description":"Placche in tecnopolimero Ral 45 lucida per scatola rettangolare colore Bianco Banquise (RAL 9016) - 2 (1+1) moduli","og_url":"https:\/\/www.ave.it\/catalog\/prodotto\/45p002bg\/","og_site_name":"AVE S.p.A.","article_publisher":"https:\/\/www.facebook.com\/aveinterruttori\/","article_modified_time":"2026-07-15T02:17:02+00:00","og_image":[{"width":1300,"height":1300,"url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000003443.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@aveinterruttori","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/45p002bg\/","url":"https:\/\/www.ave.it\/catalog\/prodotto\/45p002bg\/","name":"45P002BG - Placca lucida in tecnopolimero colore bianco banquise 2 Mod. separati","isPartOf":{"@id":"https:\/\/www.ave.it\/catalog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/45p002bg\/#primaryimage"},"image":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/45p002bg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000003443.jpg","datePublished":"2019-12-09T13:52:45+00:00","dateModified":"2026-07-15T02:17:02+00:00","description":"Placche in tecnopolimero Ral 45 lucida per scatola rettangolare colore Bianco Banquise (RAL 9016) - 2 (1+1) moduli","breadcrumb":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/45p002bg\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ave.it\/catalog\/prodotto\/45p002bg\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/45p002bg\/#primaryimage","url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000003443.jpg","contentUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000003443.jpg","width":1300,"height":1300},{"@type":"BreadcrumbList","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/45p002bg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Catalogo tecnico","item":"https:\/\/www.ave.it\/catalog\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ave.it\/catalog\/home\/"},{"@type":"ListItem","position":3,"name":"Serie civili componibili","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/serie-civili-componibili\/"},{"@type":"ListItem","position":4,"name":"Placche e armature S45","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/serie-civili-componibili\/placche-e-armature-s45\/"},{"@type":"ListItem","position":5,"name":"Placche","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/serie-civili-componibili\/placche-e-armature-s45\/placche\/"},{"@type":"ListItem","position":6,"name":"Placche Ral 45","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/serie-civili-componibili\/placche-e-armature-s45\/placche\/placche-ral-45\/"},{"@type":"ListItem","position":7,"name":"In tecnopolimero","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/serie-civili-componibili\/placche-e-armature-s45\/placche\/placche-ral-45\/in-tecnopolimero-placche-ral-45\/"},{"@type":"ListItem","position":8,"name":"Versione a 2 moduli separati","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/serie-civili-componibili\/placche-e-armature-s45\/placche\/placche-ral-45\/in-tecnopolimero-placche-ral-45\/versione-a-2-moduli-separati-in-tecnopolimero-placche-ral-45\/"},{"@type":"ListItem","position":9,"name":"45P002BG"}]},{"@type":"WebSite","@id":"https:\/\/www.ave.it\/catalog\/#website","url":"https:\/\/www.ave.it\/catalog\/","name":"AVE S.p.A.","description":"","publisher":{"@id":"https:\/\/www.ave.it\/catalog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ave.it\/catalog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.ave.it\/catalog\/#organization","name":"Ave S.p.A.","url":"https:\/\/www.ave.it\/catalog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/","url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png","contentUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png","width":330,"height":142,"caption":"Ave S.p.A."},"image":{"@id":"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aveinterruttori\/","https:\/\/x.com\/aveinterruttori","https:\/\/www.instagram.com\/aveinterruttori\/","https:\/\/www.linkedin.com\/company\/ave-spa\/","https:\/\/www.youtube.com\/user\/DominaPlusAve"]}]}},"lang":"it","translations":{"it":44543,"en":80059},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/44543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":29,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/44543\/revisions"}],"predecessor-version":[{"id":474861,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/44543\/revisions\/474861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/media\/252311"}],"wp:attachment":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/media?parent=44543"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_brand?post=44543"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_cat?post=44543"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_tag?post=44543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}