{"id":45432,"date":"2019-12-09T14:58:15","date_gmt":"2019-12-09T13:58:15","guid":{"rendered":"https:\/\/www.ave.it\/prodotto\/53aban02\/"},"modified":"2026-05-13T04:47:06","modified_gmt":"2026-05-13T02:47:06","slug":"53aban02","status":"publish","type":"product","link":"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/","title":{"rendered":"53ABAN02"},"content":{"rendered":"<p>{&#8220;Prezzo&#8221;:{&#8220;Prezzo&#8221;:&#8221;251,33&#8243;},&#8221;Descrizione&#8221;:{&#8220;Descrizione&#8221;:&#8221;Interfaccia con 2 ingressi analogici &#8211; AVEbus &#8211; 2 Mod. DIN&#8221;,&#8221;Descrizione estesa&#8221;:&#8221;Interfaccia con due ingressi analogici (0-10V e 4-20mA) per sonde e sensori. I due ingressi leggono segnali analogici in tensione (es. 0-10V), in corrente (es. 4-20mA) e possono essere configurati anche come ingressi digitali (misure di frequenza 0-2kHz) o come ingressi di rilevazione temperatura mediante NTC o termocoppia Pt100. Il dispositivo &#232; sviluppato per funzionare a logica distribuita, pu&#242; essere infatti configurato per gestire dei comandi AVEbus autonomamente in funzione del valore rilevato in ingresso, messo a confronto con cinque soglie programmabili (L0, L, M, H e H0). Inoltre il dispositivo pu&#242; essere supervisionato da un supervisore DOMINA smart IoT, dal quale oltre che visualizzare lo stato degli ingressi analogici e anche possibile impostare il valore delle soglie che ne parametrizzano il funzionamento autonomo &#8211; 2 moduli DIN&#8221;},&#8221;Dati commerciali&#8221;:{&#8220;Codice EAN13&#8243;:&#8221;8008379090754&#8243;,&#8221;Imballo standard&#8221;:&#8221;1,00&#8243;,&#8221;Imballo minimo&#8221;:&#8221;1,00&#8243;,&#8221;Codice EAN13 imb.min.&#8221;:&#8221;8008379090754&#8243;,&#8221;Lunghezza imb. min.&#8221;:&#8221;91,00&#8243;,&#8221;Larghezza imb. min.&#8221;:&#8221;37,00&#8243;,&#8221;Altezza imb. min.&#8221;:&#8221;75,00&#8243;,&#8221;Volume imb. min.&#8221;:&#8221;0,25&#8243;,&#8221;Peso imb. min.&#8221;:&#8221;91,80&#8243;,&#8221;Quantit\\u00e0 min. ordine&#8221;:&#8221;1,00&#8243;,&#8221;Riferimento Metel&#8221;:&#8221;INTERFACCIA AVEBUS 2 ING. ANALOGICI&#8221;,&#8221;Stato prodotto&#8221;:&#8221;A Magazzino&#8221;},&#8221;Capitolato&#8221;:{&#8220;Voce di capitolato&#8221;:&#8221;<\/p>\n<p>Fornitura di interfaccia tipo AVE 53ABAN02 con collegamento su bus AVEbus e due ingressi analogici gestibili in diverse configurazioni e modalit&agrave;. I due ingressi leggono segnali analogici in tensione (es. 0-10V), in corrente (es. 4-20mA) e possono essere configurati anche come ingressi digitali (misure di frequenza 0-2kHz) e\\\/o come ingressi di rilevazione temperatura mediante NTC (10k&Omega; &#8211; &szlig;=3380) o termocoppia Pt100. Il dispositivo &egrave; sviluppato per funzionare a logica distribuita, pu&ograve; essere infatti configurato per gestire dei comandi autonomamente in funzione del valore rilevato dall&rsquo;ingresso messo a confronto con cinque soglie programmabili (L0, L, M, H e H0). Inoltre il dispositivo pu&ograve; essere supervisionato per visualizzare lo stato degli ingressi analogici ed impostare il valore delle soglie che parametrizzano il funzionamento autonomo dell&rsquo;interfaccia.\\r\\n\\r\\n<\/p>\n<p>&nbsp;\\r\\n\\r\\n<\/p>\n<p>Caratteristiche tecniche:<br \/>\\r\\nContenitore: 2 moduli DIN (35 l x 89 h x 64.5 p) mm<br \/>\\r\\nGrado di protezione: IP30D con gli appositi copri morsetti in dotazione<br \/>\\r\\nAlimentazione ausiliaria da sorgente SELV: 12Vcc<br \/>\\r\\nVariazione ammessa: 10,5Vcc &divide; 14Vcc<br \/>\\r\\nAssorbimento @ 12Vcc: 30mA (ingressi analogici) | 35mA (ingressi Pt100) | 25mA (ingressi digitali)<br \/>\\r\\nImpedenza di ingresso (0-10V): 375 k&Omega;<br \/>\\r\\nImpedenza di ingresso (4-20mA): 121 &Omega;<br \/>\\r\\nTemper. e Umidit&agrave; Relat. di riferimento: 25&deg;C UR 65%<br \/>\\r\\nCampo Temper. Amb. di Funzionamento: da -10&deg;C a +50&deg;C<br \/>\\r\\nUmidit&agrave; Relativa Massima: 90% a 35&deg;C<br \/>\\r\\nAltitudine max: 2000m s.l.m.\\r\\n&#8221;},&#8221;Categorizzazione&#8221;:{&#8220;Serie&#8221;:&#8221;802&#8243;,&#8221;Divisione&#8221;:&#8221;8&#8243;,&#8221;GP&#8221;:&#8221;67&#8243;,&#8221;Classe&#8221;:&#8221;EC000794&#8243;},&#8221;Dati tecnici ETIM&#8221;:{&#8220;Tipo di montaggio&#8221;:&#8221;Canale da incasso per apparecchi&#8221;,&#8221;Tipologia&#8221;:&#8221;Modulo base&#8221;,&#8221;Numero di ingressi&#8221;:&#8221;2&#8243;,&#8221;Sistema bus EIB\\\/KNX&#8221;:&#8221;No&#8221;,&#8221;Sistema bus radio&#8221;:&#8221;No&#8221;,&#8221;Sistema bus Powernet&#8221;:&#8221;No&#8221;,&#8221;Accoppiamento bus incluso&#8221;:&#8221;Si&#8221;,&#8221;Grandezza d&#8217;entrata corrente&#8221;:&#8221;Si&#8221;,&#8221;Grandezza d&#8217;entrata tensione&#8221;:&#8221;Si&#8221;,&#8221;Numero moduli DIN&#8221;:&#8221;2&#8243;,&#8221;Altri sistemi bus&#8221;:&#8221;Altro&#8221;,&#8221;Sistema bus LON&#8221;:&#8221;No&#8221;,&#8221;Grado di protezione (IP)&#8221;:&#8221;IP41&#8243;,&#8221;Con indicatore a LED&#8221;:&#8221;Si&#8221;,&#8221;Sistema bus radio KNX&#8221;:&#8221;No&#8221;,&#8221;Min. profondit\\u00e0 della presa per apparecchi&#8221;:&#8221;- Millimetro&#8221;},&#8221;Tagliando&#8221;:{&#8220;C0670rev00&#8243;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/A000005714.pdf&#8221;},&#8221;Software&#8221;:{&#8220;EasyConfig versione 280&#8243;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/0000044787.zip&#8221;,&#8221;SFW-BSA 6.1.1.7&#8243;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/0000044784.zip&#8221;},&#8221;Immagini Articolo&#8221;:{&#8220;53ABAN02&#8243;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/A000004277.jpg&#8221;},&#8221;Pagina Catalogo Commerciale&#8221;:{&#8220;Pagina catalogo Pag447&#8243;:&#8221;https:\\\/\\\/www.ave.it\\\/catalog\\\/import_file\\\/files\\\/D000000278.pdf&#8221;},&#8221;Data ultimo aggiornamento&#8221;:{&#8220;Data ultimo aggiornamento&#8221;:&#8221;02-03-2026&#8243;}}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Interfaccia con due ingressi analogici (0-10V e 4-20mA) per sonde e sensori. I due ingressi leggono segnali analogici in tensione (es. 0-10V), in corrente (es. 4-20mA) e possono essere configurati anche come ingressi digitali (misure di frequenza 0-2kHz) o come ingressi di rilevazione temperatura mediante NTC o termocoppia Pt100. Il dispositivo &#232; sviluppato per funzionare a logica distribuita, pu&#242; essere infatti configurato per gestire dei comandi AVEbus autonomamente in funzione del valore rilevato in ingresso, messo a confronto con cinque soglie programmabili (L0, L, M, H e H0). Inoltre il dispositivo pu&#242; essere supervisionato da un supervisore DOMINA smart IoT, dal quale oltre che visualizzare lo stato degli ingressi analogici e anche possibile impostare il valore delle soglie che ne parametrizzano il funzionamento autonomo &#8211; 2 moduli DIN<\/p>\n","protected":false},"featured_media":246262,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3556,3557,3558],"product_tag":[3559,3670],"class_list":{"0":"post-45432","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-domotica-e-gestione-alberghiera","7":"product_cat-domotica","8":"product_cat-comandi-e-attuatori","9":"product_tag-comandi-e-attuatori","10":"product_tag-dispositivi-di-interfaccia","12":"first","13":"instock","14":"purchasable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>53ABAN02 - Interfaccia con 2 ingressi analogici - AVEbus - 2 Mod. DIN<\/title>\n<meta name=\"description\" content=\"Interfaccia con due ingressi analogici (0-10V e 4-20mA) per sonde e sensori. I due ingressi leggono segnali analogici in tensione (es. 0-10V), in corrente (es. 4-20mA) e possono essere configurati anche come ingressi digitali (misure di frequenza 0-2kHz) o come ingressi di rilevazione temperatura mediante NTC o termocoppia Pt100. Il dispositivo &#232; sviluppato per funzionare a logica distribuita, pu&#242; essere infatti configurato per gestire dei comandi AVEbus autonomamente in funzione del valore rilevato in ingresso, messo a confronto con cinque soglie programmabili (L0, L, M, H e H0). Inoltre il dispositivo pu&#242; essere supervisionato da un supervisore DOMINA smart IoT, dal quale oltre che visualizzare lo stato degli ingressi analogici e anche possibile impostare il valore delle soglie che ne parametrizzano il funzionamento autonomo - 2 moduli DIN\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"53ABAN02 - Interfaccia con 2 ingressi analogici - AVEbus - 2 Mod. DIN\" \/>\n<meta property=\"og:description\" content=\"Interfaccia con due ingressi analogici (0-10V e 4-20mA) per sonde e sensori. I due ingressi leggono segnali analogici in tensione (es. 0-10V), in corrente (es. 4-20mA) e possono essere configurati anche come ingressi digitali (misure di frequenza 0-2kHz) o come ingressi di rilevazione temperatura mediante NTC o termocoppia Pt100. Il dispositivo &#232; sviluppato per funzionare a logica distribuita, pu&#242; essere infatti configurato per gestire dei comandi AVEbus autonomamente in funzione del valore rilevato in ingresso, messo a confronto con cinque soglie programmabili (L0, L, M, H e H0). Inoltre il dispositivo pu&#242; essere supervisionato da un supervisore DOMINA smart IoT, dal quale oltre che visualizzare lo stato degli ingressi analogici e anche possibile impostare il valore delle soglie che ne parametrizzano il funzionamento autonomo - 2 moduli DIN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/\" \/>\n<meta property=\"og:site_name\" content=\"AVE S.p.A.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aveinterruttori\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T02:47:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000004277.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@aveinterruttori\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/\",\"url\":\"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/\",\"name\":\"53ABAN02 - Interfaccia con 2 ingressi analogici - AVEbus - 2 Mod. DIN\",\"isPartOf\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000004277.jpg\",\"datePublished\":\"2019-12-09T13:58:15+00:00\",\"dateModified\":\"2026-05-13T02:47:06+00:00\",\"description\":\"Interfaccia con due ingressi analogici (0-10V e 4-20mA) per sonde e sensori. I due ingressi leggono segnali analogici in tensione (es. 0-10V), in corrente (es. 4-20mA) e possono essere configurati anche come ingressi digitali (misure di frequenza 0-2kHz) o come ingressi di rilevazione temperatura mediante NTC o termocoppia Pt100. Il dispositivo &#232; sviluppato per funzionare a logica distribuita, pu&#242; essere infatti configurato per gestire dei comandi AVEbus autonomamente in funzione del valore rilevato in ingresso, messo a confronto con cinque soglie programmabili (L0, L, M, H e H0). Inoltre il dispositivo pu&#242; essere supervisionato da un supervisore DOMINA smart IoT, dal quale oltre che visualizzare lo stato degli ingressi analogici e anche possibile impostare il valore delle soglie che ne parametrizzano il funzionamento autonomo - 2 moduli DIN\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/#primaryimage\",\"url\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000004277.jpg\",\"contentUrl\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000004277.jpg\",\"width\":1300,\"height\":1300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Catalogo tecnico\",\"item\":\"https:\/\/www.ave.it\/catalog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\/\/www.ave.it\/catalog\/home\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Domotica Residenziale e Terziario\",\"item\":\"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/domotica-e-gestione-alberghiera\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"53ABAN02\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ave.it\/catalog\/#website\",\"url\":\"https:\/\/www.ave.it\/catalog\/\",\"name\":\"AVE S.p.A.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ave.it\/catalog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ave.it\/catalog\/#organization\",\"name\":\"Ave S.p.A.\",\"url\":\"https:\/\/www.ave.it\/catalog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png\",\"contentUrl\":\"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png\",\"width\":330,\"height\":142,\"caption\":\"Ave S.p.A.\"},\"image\":{\"@id\":\"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/aveinterruttori\/\",\"https:\/\/x.com\/aveinterruttori\",\"https:\/\/www.instagram.com\/aveinterruttori\/\",\"https:\/\/www.linkedin.com\/company\/ave-spa\/\",\"https:\/\/www.youtube.com\/user\/DominaPlusAve\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"53ABAN02 - Interfaccia con 2 ingressi analogici - AVEbus - 2 Mod. DIN","description":"Interfaccia con due ingressi analogici (0-10V e 4-20mA) per sonde e sensori. I due ingressi leggono segnali analogici in tensione (es. 0-10V), in corrente (es. 4-20mA) e possono essere configurati anche come ingressi digitali (misure di frequenza 0-2kHz) o come ingressi di rilevazione temperatura mediante NTC o termocoppia Pt100. Il dispositivo &#232; sviluppato per funzionare a logica distribuita, pu&#242; essere infatti configurato per gestire dei comandi AVEbus autonomamente in funzione del valore rilevato in ingresso, messo a confronto con cinque soglie programmabili (L0, L, M, H e H0). Inoltre il dispositivo pu&#242; essere supervisionato da un supervisore DOMINA smart IoT, dal quale oltre che visualizzare lo stato degli ingressi analogici e anche possibile impostare il valore delle soglie che ne parametrizzano il funzionamento autonomo - 2 moduli DIN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/","og_locale":"it_IT","og_type":"article","og_title":"53ABAN02 - Interfaccia con 2 ingressi analogici - AVEbus - 2 Mod. DIN","og_description":"Interfaccia con due ingressi analogici (0-10V e 4-20mA) per sonde e sensori. I due ingressi leggono segnali analogici in tensione (es. 0-10V), in corrente (es. 4-20mA) e possono essere configurati anche come ingressi digitali (misure di frequenza 0-2kHz) o come ingressi di rilevazione temperatura mediante NTC o termocoppia Pt100. Il dispositivo &#232; sviluppato per funzionare a logica distribuita, pu&#242; essere infatti configurato per gestire dei comandi AVEbus autonomamente in funzione del valore rilevato in ingresso, messo a confronto con cinque soglie programmabili (L0, L, M, H e H0). Inoltre il dispositivo pu&#242; essere supervisionato da un supervisore DOMINA smart IoT, dal quale oltre che visualizzare lo stato degli ingressi analogici e anche possibile impostare il valore delle soglie che ne parametrizzano il funzionamento autonomo - 2 moduli DIN","og_url":"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/","og_site_name":"AVE S.p.A.","article_publisher":"https:\/\/www.facebook.com\/aveinterruttori\/","article_modified_time":"2026-05-13T02:47:06+00:00","og_image":[{"width":1300,"height":1300,"url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000004277.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@aveinterruttori","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/","url":"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/","name":"53ABAN02 - Interfaccia con 2 ingressi analogici - AVEbus - 2 Mod. DIN","isPartOf":{"@id":"https:\/\/www.ave.it\/catalog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/#primaryimage"},"image":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000004277.jpg","datePublished":"2019-12-09T13:58:15+00:00","dateModified":"2026-05-13T02:47:06+00:00","description":"Interfaccia con due ingressi analogici (0-10V e 4-20mA) per sonde e sensori. I due ingressi leggono segnali analogici in tensione (es. 0-10V), in corrente (es. 4-20mA) e possono essere configurati anche come ingressi digitali (misure di frequenza 0-2kHz) o come ingressi di rilevazione temperatura mediante NTC o termocoppia Pt100. Il dispositivo &#232; sviluppato per funzionare a logica distribuita, pu&#242; essere infatti configurato per gestire dei comandi AVEbus autonomamente in funzione del valore rilevato in ingresso, messo a confronto con cinque soglie programmabili (L0, L, M, H e H0). Inoltre il dispositivo pu&#242; essere supervisionato da un supervisore DOMINA smart IoT, dal quale oltre che visualizzare lo stato degli ingressi analogici e anche possibile impostare il valore delle soglie che ne parametrizzano il funzionamento autonomo - 2 moduli DIN","breadcrumb":{"@id":"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/#primaryimage","url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000004277.jpg","contentUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2023\/07\/a000004277.jpg","width":1300,"height":1300},{"@type":"BreadcrumbList","@id":"https:\/\/www.ave.it\/catalog\/prodotto\/53aban02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Catalogo tecnico","item":"https:\/\/www.ave.it\/catalog\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ave.it\/catalog\/home\/"},{"@type":"ListItem","position":3,"name":"Domotica Residenziale e Terziario","item":"https:\/\/www.ave.it\/catalog\/categoria-prodotto\/domotica-e-gestione-alberghiera\/"},{"@type":"ListItem","position":4,"name":"53ABAN02"}]},{"@type":"WebSite","@id":"https:\/\/www.ave.it\/catalog\/#website","url":"https:\/\/www.ave.it\/catalog\/","name":"AVE S.p.A.","description":"","publisher":{"@id":"https:\/\/www.ave.it\/catalog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ave.it\/catalog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.ave.it\/catalog\/#organization","name":"Ave S.p.A.","url":"https:\/\/www.ave.it\/catalog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/","url":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png","contentUrl":"https:\/\/www.ave.it\/catalog\/wp-content\/uploads\/2018\/11\/logo-ave.png","width":330,"height":142,"caption":"Ave S.p.A."},"image":{"@id":"https:\/\/www.ave.it\/catalog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aveinterruttori\/","https:\/\/x.com\/aveinterruttori","https:\/\/www.instagram.com\/aveinterruttori\/","https:\/\/www.linkedin.com\/company\/ave-spa\/","https:\/\/www.youtube.com\/user\/DominaPlusAve"]}]}},"lang":"it","translations":{"it":45432,"en":79018},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/45432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":31,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/45432\/revisions"}],"predecessor-version":[{"id":458750,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product\/45432\/revisions\/458750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/media\/246262"}],"wp:attachment":[{"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/media?parent=45432"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_brand?post=45432"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_cat?post=45432"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ave.it\/catalog\/wp-json\/wp\/v2\/product_tag?post=45432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}